{"id":14334,"date":"2025-10-03T14:22:08","date_gmt":"2025-10-03T12:22:08","guid":{"rendered":"https:\/\/www.belgique-abonnements.be\/?post_type=product&#038;p=14334"},"modified":"2026-01-02T18:34:04","modified_gmt":"2026-01-02T17:34:04","slug":"cine-tele-revue","status":"publish","type":"product","link":"https:\/\/www.belgique-abonnements.be\/fr\/produit\/cine-tele-revue\/","title":{"rendered":"Cin\u00e9-T\u00e9l\u00e9-Revue"},"content":{"rendered":"<p><strong>Description du magazine :<\/strong><\/p>\n<p><b><i><span style=\"font-family: 'Calibri',sans-serif; color: black;\">Le guide TV n\u00b01 en Belgique !<\/span><\/i><\/b><\/p>\n<p><i><span style=\"font-family: 'Calibri',sans-serif; color: black;\">Chaque semaine, retrouvez le meilleur de la t\u00e9l\u00e9 avec des programmes complets et faciles \u00e0 consulter, des pages de jeux, l\u2019actu des stars et des s\u00e9ries, des interviews exclusives et des rubriques vari\u00e9es (cin\u00e9ma, culture, sant\u00e9, bien-\u00eatre, loisirs). Recevez chaque semaine votre magazine Cin\u00e9-T\u00e9l\u00e9-Revue\u00a0directement dans votre bo\u00eete aux lettres et acc\u00e9dez instantan\u00e9ment \u00e0 sa version digitale, o\u00f9 que vous soyez.<\/span><\/i><\/p>\n<p><strong>Inclus dans l&rsquo;abonnement :\u00a0<\/strong><\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>Votre\u00a0magazine papier\u00a0livr\u00e9 chaque semaine \u00e0 votre domicile<\/li>\n<li>La\u00a0version num\u00e9rique de votre magazine\u00a0chaque semaine<\/li>\n<li>L&rsquo;acc\u00e8s aux offres et avantages exclusifs du Club Abonn\u00e9s<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Description du magazine : Le guide TV n\u00b01 en Belgique ! Chaque semaine, retrouvez le meilleur de la t\u00e9l\u00e9 avec des programmes complets et faciles \u00e0 consulter, des pages de jeux, l\u2019actu des stars et des s\u00e9ries, des interviews exclusives et des rubriques vari\u00e9es (cin\u00e9ma, culture, sant\u00e9, bien-\u00eatre, loisirs). Recevez chaque semaine votre magazine Cin\u00e9-T\u00e9l\u00e9-Revue\u00a0directement [&hellip;]<\/p>\n","protected":false},"featured_media":14338,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[99,101],"product_tag":[],"class_list":["post-14334","product","type-product","status-publish","has-post-thumbnail","product_cat-people","product_cat-tele","pa_duree-1-an","pa_duree-6-mois","pa_langue-francais","first","instock","sale","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.belgique-abonnements.be\/fr\/wp-json\/wp\/v2\/product\/14334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.belgique-abonnements.be\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.belgique-abonnements.be\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":4,"href":"https:\/\/www.belgique-abonnements.be\/fr\/wp-json\/wp\/v2\/product\/14334\/revisions"}],"predecessor-version":[{"id":14540,"href":"https:\/\/www.belgique-abonnements.be\/fr\/wp-json\/wp\/v2\/product\/14334\/revisions\/14540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.belgique-abonnements.be\/fr\/wp-json\/wp\/v2\/media\/14338"}],"wp:attachment":[{"href":"https:\/\/www.belgique-abonnements.be\/fr\/wp-json\/wp\/v2\/media?parent=14334"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.belgique-abonnements.be\/fr\/wp-json\/wp\/v2\/product_brand?post=14334"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.belgique-abonnements.be\/fr\/wp-json\/wp\/v2\/product_cat?post=14334"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.belgique-abonnements.be\/fr\/wp-json\/wp\/v2\/product_tag?post=14334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}